{"id":17357,"date":"2021-03-20T10:26:56","date_gmt":"2021-03-20T13:26:56","guid":{"rendered":"https:\/\/dannybia.com\/dannys\/?p=17357"},"modified":"2023-02-18T11:39:58","modified_gmt":"2023-02-18T14:39:58","slug":"pentateuco-genesis","status":"publish","type":"post","link":"https:\/\/dannybia.com\/dannys\/pentateuco-genesis\/","title":{"rendered":"Pentateuco &#8211; G\u00eanesis"},"content":{"rendered":"<h1>Pentateuco &#8211; G\u00eanesis<\/h1>\n<h3>Velho Testamento<\/h3>\n<p align=\"justify\"><strong>Autor:<\/strong> Mois\u00e9s, comumente aceito.<\/p>\n<p align=\"justify\"><strong>Quando foi Escrito<\/strong>: 1450 &#8211; 1410 a.C.<\/p>\n<p align=\"justify\"><strong>O Livro das Origens:<\/strong><br \/>\n\u00c9 um registro do come\u00e7o de tudo, da origem do nosso Universo. O g\u00eanero humano, o pecado e suas manifesta\u00e7\u00f5es, a reden\u00e7\u00e3o, a vida em fam\u00edlia, a corrup\u00e7\u00e3o da sociedade, os patriarcas, os profetas, as na\u00e7\u00f5es, os diferentes idiomas, a ra\u00e7a hebraica, etc.<br \/>\nOs primeiros cap\u00edtulos do livro t\u00eam estado continuamente sob fogo da cr\u00edtica moderna, mas os fatos que apresentam, quando corretamente interpretados e entendidos, jamais t\u00eam sido negados.<br \/>\nN\u00e3o \u00e9 prop\u00f3sito do autor de G\u00eanesis dar um relato detalhado da cria\u00e7\u00e3o. Ele dedica somente um cap\u00edtulo a esse tema (s\u00f3 um esbo\u00e7o contendo alguns fatos fundamentais), enquanto dedica trinta e oito cap\u00edtulos \u00e0 hist\u00f3ria do povo escolhido.<\/p>\n<p align=\"justify\"><strong>Tema Principal:<\/strong> O pecado do homem e os passos iniciais destinados \u00e0 sua reden\u00e7\u00e3o, mediante uma alian\u00e7a divina feita com uma ra\u00e7a escolhida, cuja hist\u00f3ria primitiva ali se descreve.<\/p>\n<p align=\"justify\"><strong>Palavra Chave:<\/strong> Come\u00e7o.<\/p>\n<p align=\"justify\"><strong>Primeira Promessa Messi\u00e2nica<\/strong>: Genesis 3.15.<\/p>\n<p align=\"justify\"><strong>Sinopse:<\/strong><\/p>\n<p align=\"justify\"><span class=\"img-lef\"><\/span> <strong>Parte I<\/strong>.<br \/>\n<span class=\"img-lef-20\"><\/span> A hist\u00f3ria da cria\u00e7\u00e3o<\/strong><br \/>\n<span class=\"img-lef-40\"><\/span> Do nosso Universo, cap\u00edtulo 1:1-25<br \/>\n<span class=\"img-lef-40\"><\/span> Do homem, cap\u00edtulos 1:26-31; 2:18-24<\/p>\n<p align=\"justify\"><span class=\"img-lef\"><\/span> <strong>Parte II<\/strong>.<br \/>\n<span class=\"img-lef-20\"><\/span> A hist\u00f3ria do homem primitivo<\/strong><br \/>\n<span class=\"img-lef-40\"><\/span> A tenta\u00e7\u00e3o e a queda, a personalidade e o car\u00e1ter do tentador, o castigo do pecado, e a promessa do Redentor vindouro, cap\u00edtulo 3.<br \/>\n<span class=\"img-lef-60\"><\/span> A hist\u00f3ria de Caim e Abel, cap\u00edtulo 4.<br \/>\n<span class=\"img-lef-60\"><\/span> A genealogia e morte dos patriarcas, cap\u00edtulo 5.<br \/>\n<span class=\"img-lef-60\"><\/span> Os sucessos relacionados com o dil\u00favio, cap\u00edtulos 6-8.<br \/>\n<span class=\"img-lef-60\"><\/span> A alian\u00e7a do arco-\u00edris e o pecado de No\u00e9, cap\u00edtulo 9.<br \/>\n<span class=\"img-lef-60\"><\/span> Os descendentes de No\u00e9 , cap\u00edtulo 10.<br \/>\n<span class=\"img-lef-60\"><\/span> A confus\u00e3o da l\u00edngua em Babel, cap\u00edtulo 11.<\/p>\n<p align=\"justify\"><span class=\"img-lef\"><\/span> <strong>Parte III<\/strong>.<br \/>\n<span class=\"img-lef-20\"><\/span> A hist\u00f3ria do povo escolhido<\/strong><\/p>\n<p align=\"justify\"><span class=\"img-lef-40\"><\/span> <strong>A vida de Abra\u00e3o:<\/strong><br \/>\n<span class=\"img-lef-60\"><\/span> Seu chamado divino, cap\u00edtulo 12.<br \/>\n<span class=\"img-lef-60\"><\/span> A hist\u00f3ria de Abra\u00e3o e L\u00f3, cap\u00edtulos 13-14.<br \/>\n<span class=\"img-lef-60\"><\/span> As revela\u00e7\u00f5es divinas e as promessas a Abra\u00e3o, particularmente a promessa de um filho, da posse da Terra Santa, e de uma grande posteridade, cap\u00edtulos 15-17.<br \/>\n<span class=\"img-lef-60\"><\/span> Sua intercess\u00e3o em favor das cidades da plan\u00edcie, e a destrui\u00e7\u00e3o delas, cap\u00edtulos 18-19.<br \/>\n<span class=\"img-lef-60\"><\/span> Sua vida em Gerar, e o cumprimento da promessa de um filho no nascimento de Isaque, cap\u00edtulos 20-21.<br \/>\n<span class=\"img-lef-50\"><\/span> A prova da sua obedi\u00eancia por ocasi\u00e3o da ordem divina de sacrificar a Isaque, cap\u00edtulo 22.<\/p>\n<p align=\"justify\"><span class=\"img-lef-20\"><\/span> <strong>A vida de Isaque:<\/strong><br \/>\n<span class=\"img-lef-40\"><\/span> Seu nascimento, cap\u00edtulo 21.3.<br \/>\n<span class=\"img-lef-40\"><\/span> Seu casamento, cap\u00edtulo 24.<br \/>\n<span class=\"img-lef-40\"><\/span> O nascimento de seus filhos Jac\u00f3 e Esa\u00fa, cap\u00edtulo 25:20-26.<br \/>\n<span class=\"img-lef-40\"><\/span> Seus \u00faltimos anos, cap\u00edtulos 26-27.<\/p>\n<p align=\"justify\"><span class=\"img-lef-20\"><\/span> <strong>A vida de Jac\u00f3<\/strong><br \/>\n<span class=\"img-lef-40\"><\/span> Sua ast\u00facia para adquirir o direito de primogenitura, cap\u00edtulo 27:1-29<br \/>\n<span class=\"img-lef-40\"><\/span> Sua vis\u00e3o da escada celestial, 28:10-22<br \/>\n<span class=\"img-lef-40\"><\/span> Os incidentes relacionados com o seu matrim\u00f4nio e sua vida em Pad\u00e3-Ar\u00e3, cap\u00edtulos 29-31.<\/p>\n<p align=\"justify\"><span class=\"img-lef-20\"><\/span> <strong>A vida de Esa\u00fa<\/strong> o filho mais velho de Isaque, cap\u00edtulos 25-27.<\/p>\n<p align=\"justify\"><span class=\"img-lef-20\"><\/span> <strong>A vida de Jos\u00e9<\/strong>, aquele cujos sonhos converteram-se em realidade. Os \u00faltimos dias de Jac\u00f3, e a descida ao Egito da fam\u00edlia escolhida, cap\u00edtulos 37-50.<\/p>\n<p align=\"justify\"><strong>Nomes Preeminentes Relacionados:<\/strong><br \/>\n<span class=\"img-lef-20\"><\/span> Ad\u00e3o e Eva.<br \/>\n<span class=\"img-lef-20\"><\/span> Caim e Abel.<br \/>\n<span class=\"img-lef-20\"><\/span> Abra\u00e3o e L\u00f3.<br \/>\n<span class=\"img-lef-20\"><\/span> Isaque e Ismael.<br \/>\n<span class=\"img-lef-20\"><\/span> Esa\u00fa e Jac\u00f3.<br \/>\n<span class=\"img-lef-20\"><\/span> Jos\u00e9 e seus filhos.<\/p>\n<p align=\"justify\"><strong>Cinco Grandes Personagens Espirituais:<\/strong><br \/>\n<span class=\"img-lef-20\"><\/span> <strong>1.<\/strong> Enoque, o homem que &#8220;caminhou com Deus&#8221;.<br \/>\n<span class=\"img-lef-20\"><\/span> <strong>2.<\/strong> No\u00e9, o construtor da arca.<br \/>\n<span class=\"img-lef-20\"><\/span> <strong>3.<\/strong> Abra\u00e3o, o pai dos fi\u00e9is.<br \/>\n<span class=\"img-lef-20\"><\/span> <strong>4.<\/strong> Jac\u00f3, o homem cuja vida foi transformada pela ora\u00e7\u00e3o.<br \/>\n<span class=\"img-lef-20\"><\/span> <strong>5.<\/strong> Jos\u00e9, o filho de Jac\u00f3, que de escravo se tornou em governador do Egito.<\/p>\n<p align=\"justify\"><strong>A Li\u00e7\u00e3o das Idades:<\/strong><br \/>\n<span class=\"img-lef-20\"><\/span> A B\u00edblia come\u00e7a com a humanidade arruinada: o para\u00edso perdido, cap\u00edtulo 3.<br \/>\n<span class=\"img-lef-20\"><\/span> A institui\u00e7\u00e3o do plano de salva\u00e7\u00e3o, cap\u00edtulo 3:15.<br \/>\n<span class=\"img-lef-20\"><\/span> A B\u00edblia termina com a promessa cumprida: o para\u00edso recuperado. (Apocalipse 21:22).<\/p>\n<p align=\"center\"><a href=\"https:\/\/dannybia.com\/dannys\/biblia-sagrada\/\" class=\"su-button su-button-style-3d\" style=\"color:#FFFFFF;background-color:#00aba5;border-color:#008984;border-radius:5px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4dc5c0;border-radius:5px;text-shadow:none\"> Voltar ao \u00cdndice<\/span><\/a> <a href=\"https:\/\/dannybia.com\/dannys\/pentateuco-exodo\/\" class=\"su-button su-button-style-3d\" style=\"color:#FFFFFF;background-color:#00aba5;border-color:#008984;border-radius:5px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4dc5c0;border-radius:5px;text-shadow:none\"> \u00caxodo<\/span><\/a>\n<div class='grid-row clearfix'><div class='grid-col grid-col-12'><section class='cws-widget'><section class='cws_widget_content'> \t<div class=\"testimonial \">\n\t\t<div class='clearfix'>\n\t\t\t<img src='https:\/\/dannybia.com\/dannys\/wp-content\/uploads\/bfi_thumb\/Jesus-130-93-3cmh6ny6pugic3cykq7hts.jpg' alt \/>\t\t\t\t<p>\n<p align=\"justify\">No princ\u00edpio criou Deus os c\u00e9us e a terra. A terra era sem forma e vazia; e havia trevas sobre a face do abismo, mas o Esp\u00edrito de Deus pairava sobre a face das \u00e1guas. Disse Deus: haja luz. E houve luz.<\/p>\n<\/p>\t\t<\/div>\n\t\t<div class=\"author\">G\u00eanesis 1:1-3<\/div>\t<\/div>\n\t <\/section><\/section><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pentateuco &#8211; G\u00eanesis Velho Testamento Autor: Mois\u00e9s, comumente aceito. Quando foi Escrito: 1450 &#8211; 1410 a.C. O Livro das Origens: \u00c9 um registro do come\u00e7o de tudo, da origem do nosso Universo. O g\u00eanero humano, o pecado e suas manifesta\u00e7\u00f5es, a reden\u00e7\u00e3o, a vida em fam\u00edlia, a corrup\u00e7\u00e3o da sociedade, os patriarcas, os profetas, as na\u00e7\u00f5es, os diferentes idiomas, a ra\u00e7a hebraica, etc. Os primeiros cap\u00edtulos do livro t\u00eam estado continuamente sob fogo da cr\u00edtica moderna, mas os fatos que apresentam, quando corretamente interpretados e entendidos, jamais t\u00eam sido negados. N\u00e3o \u00e9 prop\u00f3sito do autor de G\u00eanesis dar um relato detalhado da cria\u00e7\u00e3o. Ele dedica somente um cap\u00edtulo a esse tema (s\u00f3 um esbo\u00e7o contendo alguns fatos fundamentais), enquanto dedica trinta e oito cap\u00edtulos \u00e0 hist\u00f3ria do povo escolhido. Tema Principal: O pecado do homem e os passos iniciais destinados \u00e0 sua reden\u00e7\u00e3o, mediante uma alian\u00e7a divina feita com uma ra\u00e7a escolhida, cuja hist\u00f3ria primitiva ali se descreve. Palavra Chave: Come\u00e7o. Primeira Promessa Messi\u00e2nica: Genesis 3.15. Sinopse: Parte I. A hist\u00f3ria da cria\u00e7\u00e3o Do nosso Universo, cap\u00edtulo 1:1-25 Do homem, cap\u00edtulos 1:26-31; 2:18-24 Parte II. A hist\u00f3ria do homem primitivo A tenta\u00e7\u00e3o e a queda, a personalidade e o car\u00e1ter do tentador, o castigo do pecado, e a promessa do Redentor vindouro, cap\u00edtulo 3. A hist\u00f3ria de Caim e Abel, cap\u00edtulo 4. A genealogia e morte dos patriarcas, cap\u00edtulo 5. Os sucessos relacionados com o dil\u00favio, cap\u00edtulos 6-8. A alian\u00e7a do arco-\u00edris e o pecado de No\u00e9, cap\u00edtulo 9. Os descendentes de No\u00e9 , cap\u00edtulo 10. A confus\u00e3o da l\u00edngua em Babel, cap\u00edtulo 11. Parte III. A hist\u00f3ria do povo escolhido A vida de Abra\u00e3o: Seu chamado divino, cap\u00edtulo 12. A hist\u00f3ria de Abra\u00e3o e L\u00f3, cap\u00edtulos 13-14. As revela\u00e7\u00f5es divinas e as promessas a Abra\u00e3o, particularmente a promessa de um filho, da posse da Terra Santa, e de uma grande posteridade, cap\u00edtulos 15-17. Sua intercess\u00e3o em favor das cidades da plan\u00edcie, e a destrui\u00e7\u00e3o delas, cap\u00edtulos 18-19. Sua vida em Gerar, e o cumprimento da promessa de um filho no nascimento de Isaque, cap\u00edtulos 20-21. A prova da sua obedi\u00eancia por ocasi\u00e3o da ordem divina de sacrificar a Isaque, cap\u00edtulo 22. A vida de Isaque: Seu nascimento, cap\u00edtulo 21.3. Seu casamento, cap\u00edtulo 24. O nascimento de seus filhos Jac\u00f3 e Esa\u00fa, cap\u00edtulo 25:20-26. Seus \u00faltimos anos, cap\u00edtulos 26-27. A vida de Jac\u00f3 Sua ast\u00facia para adquirir o direito de primogenitura, cap\u00edtulo 27:1-29 Sua vis\u00e3o da escada celestial, 28:10-22 Os incidentes relacionados com o seu matrim\u00f4nio e sua vida em Pad\u00e3-Ar\u00e3, cap\u00edtulos 29-31. A vida de Esa\u00fa o filho mais velho de Isaque, cap\u00edtulos 25-27. A vida de Jos\u00e9, aquele cujos sonhos converteram-se em realidade. Os \u00faltimos dias de Jac\u00f3, e a descida ao Egito da fam\u00edlia escolhida, cap\u00edtulos 37-50. Nomes Preeminentes Relacionados: Ad\u00e3o e Eva. Caim e Abel. Abra\u00e3o e L\u00f3. Isaque e Ismael. Esa\u00fa e Jac\u00f3. Jos\u00e9 e seus filhos. Cinco Grandes Personagens Espirituais: 1. Enoque, o homem que &#8220;caminhou com Deus&#8221;. 2. No\u00e9, o construtor da arca. 3. Abra\u00e3o, o pai dos fi\u00e9is. 4. Jac\u00f3, o homem cuja vida foi transformada pela ora\u00e7\u00e3o. 5. Jos\u00e9, o filho de Jac\u00f3, que de escravo se tornou em governador do Egito. A Li\u00e7\u00e3o das Idades: A B\u00edblia come\u00e7a com a humanidade arruinada: o para\u00edso perdido, cap\u00edtulo 3. A institui\u00e7\u00e3o do plano de salva\u00e7\u00e3o, cap\u00edtulo 3:15. A B\u00edblia termina com a promessa cumprida: o para\u00edso recuperado. (Apocalipse 21:22).<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1182,116,3],"tags":[374,113,995,112,1159,1158,1157],"class_list":["post-17357","post","type-post","status-publish","format-standard","hentry","category-biblia-sagrada","category-estudos-biblicos","category-news","tag-biblia-sagrada","tag-deus","tag-genesis","tag-jesus","tag-pentateuco","tag-pentateuco-genesis","tag-velho-testamento"],"_links":{"self":[{"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/posts\/17357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/comments?post=17357"}],"version-history":[{"count":0,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/posts\/17357\/revisions"}],"wp:attachment":[{"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/media?parent=17357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/categories?post=17357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/tags?post=17357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}