{"id":17008,"date":"2021-03-13T10:02:51","date_gmt":"2021-03-13T13:02:51","guid":{"rendered":"https:\/\/dannybia.com\/dannys\/?p=17008"},"modified":"2023-10-17T11:07:37","modified_gmt":"2023-10-17T14:07:37","slug":"filemom","status":"publish","type":"post","link":"https:\/\/dannybia.com\/dannys\/filemom\/","title":{"rendered":"Filemom"},"content":{"rendered":"<h1>Filemom<\/h1>\n<div class='grid-row clearfix'><div class='grid-col grid-col-12'><section class='cws-widget'><section class='cws_widget_content'>\n<h3><span class=\"red\">[\u00a0<a href=\"#1\">1<\/a>\u00a0]<\/h3>\n<\/section><\/section><\/div>\n<p align=\"right\"><a href=\"https:\/\/dannybia.com\/dannys\/biblia-online\/\" class=\"su-button su-button-style-3d\" style=\"color:#FFFFFF;background-color:#00aba5;border-color:#008984;border-radius:5px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4dc5c0;border-radius:5px;text-shadow:none\"> Voltar ao \u00cdndice<\/span><\/a>\n<h3><a id=\"1\"><\/a>Filemom 1<\/h3>\n<ol>\n<li>Paulo, prisioneiro de Cristo Jesus, e o irm\u00e3o Tim\u00f3teo, ao amado Filemom, nosso companheiro de trabalho,<\/li>\n<li>e \u00e0 nossa irm\u00e3 \u00c1fia, e a Arquipo, nosso companheiro de lutas, e \u00e0 igreja que est\u00e1 em tua casa:<\/li>\n<li>Gra\u00e7as a v\u00f3s, e paz da parte de Deus nosso Pai, e do Senhor Jesus Cristo.<\/li>\n<li>Sempre dou gra\u00e7as ao meu Deus, lembrando-me de ti nas minhas ora\u00e7\u00f5es,<\/li>\n<li>ao ouvir falar do amor e da f\u00e9 que tens para com o Senhor Jesus e para com todos os santos;<\/li>\n<li>para que a comunica\u00e7\u00e3o da tua f\u00e9 se torne eficaz, no pleno conhecimento de todo o bem que em n\u00f3s h\u00e1 para com Cristo.<\/li>\n<li>Pois tive grande gozo e consola\u00e7\u00e3o no teu amor, porque por ti, irm\u00e3o, os cora\u00e7\u00f5es dos santos t\u00eam sido reanimados.<\/li>\n<li>Pelo que, embora tenha em Cristo plena liberdade para te mandar o que conv\u00e9m,<\/li>\n<li>todavia prefiro rogar-te por esse teu amor, sendo eu como sou, Paulo o velho, e agora at\u00e9 prisioneiro de Cristo Jesus,<\/li>\n<li>sim, rogo-te por meu filho On\u00e9simo, que gerei nas minhas pris\u00f5es;<\/li>\n<li>o qual outrora te foi in\u00fatil, mas agora a ti e a mim \u00e9 muito \u00fatil;<\/li>\n<li>eu to torno a enviar, a ele que \u00e9 o meu pr\u00f3prio cora\u00e7\u00e3o.<\/li>\n<li>Eu bem quisera ret\u00ea-lo comigo, para que em teu lugar me servisse nas pris\u00f5es do evangelho;<\/li>\n<li>mas sem o teu consentimento nada quis fazer, para que o teu benef\u00edcio n\u00e3o fosse como por for\u00e7a, mas, sim, espont\u00e2neo.<\/li>\n<li>Porque bem pode ser que ele se tenha separado de ti por algum tempo, para que o recobrasses para sempre,<\/li>\n<li>n\u00e3o j\u00e1 como escravo, antes mais do que escravo, como irm\u00e3o amado, particularmente de mim, e quanto mais de ti, tanto na carne como tamb\u00e9m no Senhor.<\/li>\n<li>Assim pois, se me tens por companheiro, recebe-o como a mim mesmo.<\/li>\n<li>E, se te fez algum dano, ou te deve alguma coisa, lan\u00e7a-o minha conta.<\/li>\n<li>Eu, Paulo, de meu pr\u00f3prio punho o escrevo, eu o pagarei, para n\u00e3o te dizer que ainda a ti mesmo a mim te deves.<\/li>\n<li>Sim, irm\u00e3o, eu quisera regozijar-me de ti no Senhor; reanima o meu cora\u00e7\u00e3o em Cristo.<\/li>\n<li>Escrevo-te confiado na tua obedi\u00eancia, sabendo que far\u00e1s ainda mais do que pe\u00e7o.<\/li>\n<li>E ao mesmo tempo, prepara-me tamb\u00e9m pousada, pois espero que pelas vossas ora\u00e7\u00f5es hei de ser concedido.<\/li>\n<li>Sa\u00fada-te Epafras, meu companheiro de pris\u00e3o em Cristo Jesus,<\/li>\n<li>assim como Marcos, Aristarco, Demas e Lucas, meus cooperadores.<\/li>\n<li>A gra\u00e7a do Senhor Jesus Cristo seja com o vosso esp\u00edrito.<\/li>\n<\/ol>\n<p align=\"center\"><a href=\"https:\/\/dannybia.com\/dannys\/tito\/\" class=\"su-button su-button-style-3d\" style=\"color:#FFFFFF;background-color:#00aba5;border-color:#008984;border-radius:5px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4dc5c0;border-radius:5px;text-shadow:none\"> Tito<\/span><\/a> <a href=\"https:\/\/dannybia.com\/dannys\/hebreus\/\" class=\"su-button su-button-style-3d\" style=\"color:#FFFFFF;background-color:#00aba5;border-color:#008984;border-radius:5px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4dc5c0;border-radius:5px;text-shadow:none\"> Hebreus<\/span><\/a>\n<div class='grid-row clearfix'><\/div><div class='grid-col grid-col-12'><section class='cws-widget'><section class='cws_widget_content'> \t<div class=\"testimonial \">\n\t\t<div class='clearfix'>\n\t\t\t<img src='https:\/\/dannybia.com\/dannys\/wp-content\/uploads\/bfi_thumb\/Jesus-130-93-3cmh6ny6pugic3cykq7hts.jpg' alt \/>\t\t\t\t<p>\n<p align=\"justify\">Porque bem pode ser que ele se tenha separado de ti por algum tempo, para que o recobrasses para sempre, n\u00e3o j\u00e1 como escravo, antes mais do que escravo, como irm\u00e3o amado, particularmente de mim, e quanto mais de ti, tanto na carne como tamb\u00e9m no Senhor. Assim pois, se me tens por companheiro, recebe-o como a mim mesmo.<\/p>\n<\/p>\t\t<\/div>\n\t\t<div class=\"author\">Filemom 1:15-17<\/div>\t<\/div>\n\t <\/section><\/section><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Filemom<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[994,1182,3],"tags":[996,374,113,1132,1262,112,1133],"class_list":["post-17008","post","type-post","status-publish","format-standard","hentry","category-biblia-online","category-biblia-sagrada","category-news","tag-biblia-online","tag-biblia-sagrada","tag-deus","tag-filemom","tag-filemon","tag-jesus","tag-philemon"],"_links":{"self":[{"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/posts\/17008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/comments?post=17008"}],"version-history":[{"count":0,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/posts\/17008\/revisions"}],"wp:attachment":[{"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/media?parent=17008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/categories?post=17008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dannybia.com\/dannys\/wp-json\/wp\/v2\/tags?post=17008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}